{"id":2893,"date":"2024-07-02T18:25:17","date_gmt":"2024-07-02T16:25:17","guid":{"rendered":"https:\/\/avilacomp-sp.tecnologia.bo\/?post_type=tramite&#038;p=2893"},"modified":"2024-08-02T00:26:51","modified_gmt":"2024-08-01T22:26:51","slug":"plan-institucional-de-implementacion-de-gobierno-electronico","status":"publish","type":"tramite","link":"https:\/\/avilacomp-sp.tecnologia.bo\/index.php\/tramite\/plan-institucional-de-implementacion-de-gobierno-electronico\/","title":{"rendered":"Tramite 2"},"featured_media":0,"template":"","class_list":["post-2893","tramite","type-tramite","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/avilacomp-sp.tecnologia.bo\/index.php\/wp-json\/wp\/v2\/tramite\/2893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avilacomp-sp.tecnologia.bo\/index.php\/wp-json\/wp\/v2\/tramite"}],"about":[{"href":"https:\/\/avilacomp-sp.tecnologia.bo\/index.php\/wp-json\/wp\/v2\/types\/tramite"}],"wp:attachment":[{"href":"https:\/\/avilacomp-sp.tecnologia.bo\/index.php\/wp-json\/wp\/v2\/media?parent=2893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}